{"id":2829,"date":"2026-07-16T14:49:38","date_gmt":"2026-07-16T14:49:38","guid":{"rendered":"https:\/\/gezginraporu.com\/index.php\/2026\/07\/16\/7-uluslararasi-kapikaya-doga-sporlari-ve-kultur-festivali-hazirliklari-devam-ediyor\/"},"modified":"2026-07-16T14:49:38","modified_gmt":"2026-07-16T14:49:38","slug":"7-uluslararasi-kapikaya-doga-sporlari-ve-kultur-festivali-hazirliklari-devam-ediyor","status":"publish","type":"post","link":"https:\/\/gezginraporu.com\/index.php\/2026\/07\/16\/7-uluslararasi-kapikaya-doga-sporlari-ve-kultur-festivali-hazirliklari-devam-ediyor\/","title":{"rendered":"7. Uluslararas\u0131 Kap\u0131kaya Do\u011fa Sporlar\u0131 ve K\u00fclt\u00fcr Festivali Haz\u0131rl\u0131klar\u0131 Devam Ediyor"},"content":{"rendered":"<p>Samsun&#8217;un Bafra il\u00e7esinde, 22-26 Temmuz tarihlerinde d\u00fczenlenecek olan 7. Uluslararas\u0131 Kap\u0131kaya Do\u011fa Sporlar\u0131 ve K\u00fclt\u00fcr Festivali i\u00e7in haz\u0131rl\u0131klar devam ediyor. Festival alan\u0131nda incelemelerde bulunan Kaymakam Mustafa Alt\u0131np\u0131nar ve Belediye Ba\u015fkan\u0131 Hamit K\u0131l\u0131\u00e7, y\u00fcr\u00fct\u00fclen \u00e7al\u0131\u015fmalar hakk\u0131nda bilgi ald\u0131.<\/p>\n<p>\u0130nceleme s\u0131ras\u0131nda Kap\u0131kaya Kanyonu&#8217;nda ger\u00e7ekle\u015ftirilecek etkinliklerde kat\u0131l\u0131mc\u0131lar\u0131n g\u00fcvenli\u011finin sa\u011flanmas\u0131, ula\u015f\u0131m, sa\u011fl\u0131k, trafik ve di\u011fer kamu hizmetlerinin koordineli bir \u015fekilde y\u00fcr\u00fct\u00fclmesi konular\u0131 de\u011ferlendirildi. Ayr\u0131ca, ilgili kurumlar\u0131n g\u00f6rev ve sorumluluklar\u0131 g\u00f6zden ge\u00e7irilerek organizasyonun sorunsuz bir \u015fekilde tamamlanmas\u0131 i\u00e7in al\u0131nacak \u00f6nlemler \u00fczerinde duruldu.<\/p>\n<p>Festivalin, il\u00e7enin ve b\u00f6lgenin tan\u0131t\u0131m\u0131na katk\u0131da bulunmas\u0131 bekleniyor. T\u00fcm kurumlar\u0131n koordineli bir \u015fekilde \u00e7al\u0131\u015farak kat\u0131l\u0131mc\u0131lar\u0131n g\u00fcvenli ve huzurlu bir deneyim ya\u015famas\u0131n\u0131 sa\u011flamak amac\u0131yla \u00e7aba g\u00f6sterdi\u011fi bildirildi.<\/p>\n<p>Do\u011faseverler ile amat\u00f6r ve profesyonel sporcular\u0131 bir araya getirecek olan festivalde, farkl\u0131 bran\u015flarda d\u00fczenlenecek yar\u0131\u015fmalarla kat\u0131l\u0131mc\u0131lara spor ve do\u011fa deneyimi sunulmas\u0131 hedefleniyor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Samsun&#8217;un Bafra il\u00e7esinde 22-26 Temmuz tarihlerinde ger\u00e7ekle\u015ftirilecek olan festival i\u00e7in haz\u0131rl\u0131klar s\u00fcr\u00fcyor. Kaymakam ve Belediye Ba\u015fkan\u0131, g\u00fcvenlik ve koordinasyon \u00f6nlemlerini de\u011ferlendirdi.<\/p>\n","protected":false},"author":1,"featured_media":2830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"manset":[],"bilesen":[],"class_list":["post-2829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turizm"],"_links":{"self":[{"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/posts\/2829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/comments?post=2829"}],"version-history":[{"count":0,"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/posts\/2829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/media\/2830"}],"wp:attachment":[{"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/media?parent=2829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/categories?post=2829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/tags?post=2829"},{"taxonomy":"manset","embeddable":true,"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/manset?post=2829"},{"taxonomy":"bilesen","embeddable":true,"href":"https:\/\/gezginraporu.com\/index.php\/wp-json\/wp\/v2\/bilesen?post=2829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}